{"id":110,"count":1,"description":"","link":"https:\/\/riabilitazioneneurocognitiva.it\/en\/project-category\/2021-rivista-riabilitazione-neurocognitiva-en\/","name":"2021","slug":"2021-rivista-riabilitazione-neurocognitiva-en","taxonomy":"dt_portfolio_category","parent":0,"meta":[],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.0 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>2021 Archivi - Riabilitazione Neurocognitiva<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/riabilitazioneneurocognitiva.it\/en\/project-category\/2021-rivista-riabilitazione-neurocognitiva-en\/\" \/>\n<meta property=\"og:locale\" content=\"en_US\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"2021 Archivi - Riabilitazione Neurocognitiva\" \/>\n<meta property=\"og:url\" content=\"https:\/\/riabilitazioneneurocognitiva.it\/en\/project-category\/2021-rivista-riabilitazione-neurocognitiva-en\/\" \/>\n<meta property=\"og:site_name\" content=\"Riabilitazione Neurocognitiva\" \/>\n<meta property=\"og:image\" content=\"https:\/\/riabilitazioneneurocognitiva.it\/wp-content\/uploads\/2021\/03\/rn-social-fb-home.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1200\" \/>\n\t<meta property=\"og:image:height\" content=\"630\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"CollectionPage\",\"@id\":\"https:\\\/\\\/riabilitazioneneurocognitiva.it\\\/en\\\/project-category\\\/2021-rivista-riabilitazione-neurocognitiva-en\\\/\",\"url\":\"https:\\\/\\\/riabilitazioneneurocognitiva.it\\\/en\\\/project-category\\\/2021-rivista-riabilitazione-neurocognitiva-en\\\/\",\"name\":\"2021 Archivi - Riabilitazione Neurocognitiva\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/riabilitazioneneurocognitiva.it\\\/en\\\/#website\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/riabilitazioneneurocognitiva.it\\\/en\\\/project-category\\\/2021-rivista-riabilitazione-neurocognitiva-en\\\/#breadcrumb\"},\"inLanguage\":\"en-US\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/riabilitazioneneurocognitiva.it\\\/en\\\/project-category\\\/2021-rivista-riabilitazione-neurocognitiva-en\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/riabilitazioneneurocognitiva.it\\\/en\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"2021\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/riabilitazioneneurocognitiva.it\\\/en\\\/#website\",\"url\":\"https:\\\/\\\/riabilitazioneneurocognitiva.it\\\/en\\\/\",\"name\":\"Riabilitazione Neurocognitiva\",\"description\":\"Centro Studi di Santorso\",\"publisher\":{\"@id\":\"https:\\\/\\\/riabilitazioneneurocognitiva.it\\\/en\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/riabilitazioneneurocognitiva.it\\\/en\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"en-US\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/riabilitazioneneurocognitiva.it\\\/en\\\/#organization\",\"name\":\"Neurocognitive Rehabilitation - Villa Miari Study Center\",\"url\":\"https:\\\/\\\/riabilitazioneneurocognitiva.it\\\/en\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\\\/\\\/riabilitazioneneurocognitiva.it\\\/en\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/riabilitazioneneurocognitiva.it\\\/wp-content\\\/uploads\\\/2018\\\/12\\\/rnc-mobile-logo-hd.png\",\"contentUrl\":\"https:\\\/\\\/riabilitazioneneurocognitiva.it\\\/wp-content\\\/uploads\\\/2018\\\/12\\\/rnc-mobile-logo-hd.png\",\"width\":300,\"height\":120,\"caption\":\"Neurocognitive Rehabilitation - Villa Miari Study Center\"},\"image\":{\"@id\":\"https:\\\/\\\/riabilitazioneneurocognitiva.it\\\/en\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/it-it.facebook.com\\\/centrostudivillamiari\",\"https:\\\/\\\/www.youtube.com\\\/channel\\\/UCu7jdSSUefgLMX_NlSydUQQ\"]}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"2021 Archivi - Riabilitazione Neurocognitiva","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/riabilitazioneneurocognitiva.it\/en\/project-category\/2021-rivista-riabilitazione-neurocognitiva-en\/","og_locale":"en_US","og_type":"article","og_title":"2021 Archivi - Riabilitazione Neurocognitiva","og_url":"https:\/\/riabilitazioneneurocognitiva.it\/en\/project-category\/2021-rivista-riabilitazione-neurocognitiva-en\/","og_site_name":"Riabilitazione Neurocognitiva","og_image":[{"width":1200,"height":630,"url":"https:\/\/riabilitazioneneurocognitiva.it\/wp-content\/uploads\/2021\/03\/rn-social-fb-home.jpg","type":"image\/jpeg"}],"twitter_card":"summary_large_image","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"CollectionPage","@id":"https:\/\/riabilitazioneneurocognitiva.it\/en\/project-category\/2021-rivista-riabilitazione-neurocognitiva-en\/","url":"https:\/\/riabilitazioneneurocognitiva.it\/en\/project-category\/2021-rivista-riabilitazione-neurocognitiva-en\/","name":"2021 Archivi - Riabilitazione Neurocognitiva","isPartOf":{"@id":"https:\/\/riabilitazioneneurocognitiva.it\/en\/#website"},"breadcrumb":{"@id":"https:\/\/riabilitazioneneurocognitiva.it\/en\/project-category\/2021-rivista-riabilitazione-neurocognitiva-en\/#breadcrumb"},"inLanguage":"en-US"},{"@type":"BreadcrumbList","@id":"https:\/\/riabilitazioneneurocognitiva.it\/en\/project-category\/2021-rivista-riabilitazione-neurocognitiva-en\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/riabilitazioneneurocognitiva.it\/en\/"},{"@type":"ListItem","position":2,"name":"2021"}]},{"@type":"WebSite","@id":"https:\/\/riabilitazioneneurocognitiva.it\/en\/#website","url":"https:\/\/riabilitazioneneurocognitiva.it\/en\/","name":"Riabilitazione Neurocognitiva","description":"Centro Studi di Santorso","publisher":{"@id":"https:\/\/riabilitazioneneurocognitiva.it\/en\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/riabilitazioneneurocognitiva.it\/en\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"en-US"},{"@type":"Organization","@id":"https:\/\/riabilitazioneneurocognitiva.it\/en\/#organization","name":"Neurocognitive Rehabilitation - Villa Miari Study Center","url":"https:\/\/riabilitazioneneurocognitiva.it\/en\/","logo":{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/riabilitazioneneurocognitiva.it\/en\/#\/schema\/logo\/image\/","url":"https:\/\/riabilitazioneneurocognitiva.it\/wp-content\/uploads\/2018\/12\/rnc-mobile-logo-hd.png","contentUrl":"https:\/\/riabilitazioneneurocognitiva.it\/wp-content\/uploads\/2018\/12\/rnc-mobile-logo-hd.png","width":300,"height":120,"caption":"Neurocognitive Rehabilitation - Villa Miari Study Center"},"image":{"@id":"https:\/\/riabilitazioneneurocognitiva.it\/en\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/it-it.facebook.com\/centrostudivillamiari","https:\/\/www.youtube.com\/channel\/UCu7jdSSUefgLMX_NlSydUQQ"]}]}},"_links":{"self":[{"href":"https:\/\/riabilitazioneneurocognitiva.it\/en\/wp-json\/wp\/v2\/dt_portfolio_category\/110","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/riabilitazioneneurocognitiva.it\/en\/wp-json\/wp\/v2\/dt_portfolio_category"}],"about":[{"href":"https:\/\/riabilitazioneneurocognitiva.it\/en\/wp-json\/wp\/v2\/taxonomies\/dt_portfolio_category"}],"wp:post_type":[{"href":"https:\/\/riabilitazioneneurocognitiva.it\/en\/wp-json\/wp\/v2\/dt_portfolio?dt_portfolio_category=110"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}